﻿{"id":2248,"date":"2017-01-20T12:42:24","date_gmt":"2017-01-20T11:42:24","guid":{"rendered":"http:\/\/www.meletout.net\/corrigeur\/?p=2248"},"modified":"2024-02-19T19:32:38","modified_gmt":"2024-02-19T18:32:38","slug":"sylvie-godefroid-elle-et-elle-2","status":"publish","type":"post","link":"http:\/\/www.meletout.net\/corrigeur\/sylvie-godefroid-elle-et-elle-2\/","title":{"rendered":"Sylvie Godefroid : \u00ab\u00a0Elle et Elle\u00a0\u00bb"},"content":{"rendered":"<p style=\"text-align: left;\"><em>Une femme qui souffre, une femme qui s&rsquo;ouvre&#8230; Le silence aussi parfois : celui de dire encore un peu ce qu&rsquo;elle peut ou veut&#8230; je crois&#8230; je ne sais pas&#8230; je lis&#8230; j&rsquo;\u00e9coute&#8230; Il ferait froid si les mots n&rsquo;\u00e9taient pas enfin l\u00e0&#8230; ils se glissent&#8230; ils dansent aussi parfois&#8230; Ils pleurent ou presque&#8230; de rire&#8230; de joie&#8230; et parfois aussi tout simplement, ils pleurent&#8230; Pourquoi ? Parce qu&rsquo;il faut bien sans doute ; ou parce que c&rsquo;est comme \u00e7a. Tout ce chemin enrubann\u00e9 de vides \u00e0 combler, de n\u0153uds \u00e0 d\u00e9nouer&#8230; Tous ces cadeaux inattendus comme autant de surprises&#8230; Que voulez-vous que je vous dise ? C&rsquo;est ce pour quoi je lis&#8230; pour quoi je vis aussi parfois quand je me donne et m&rsquo;adonne moi-m\u00eame \u00e0 l&rsquo;\u00e9criture ; \u00e0 la charmante imposture de se croire enfin l\u00e0&#8230; parfois, oui, parfois. C&rsquo;est la r\u00e8gle du je : il revient quand les mots sont enfin l\u00e0. Il revient \u00e0 lui ; \u00e0 la ligne ; il revient d&rsquo;o\u00f9 l&rsquo;on ne revient pas&#8230; je crois&#8230; je ne sais pas&#8230; je vois ce que je bois&#8230; des yeux, du c\u0153ur, d&rsquo;ici et l\u00e0&#8230; d&rsquo;ailleurs sait-on jamais ce que sont tous ces mots-l\u00e0 lorsqu&rsquo;ils sont enfin l\u00e0&#8230; leur sens, leur son&#8230; oui&#8230; sait-on jamais ce qu&rsquo;ils sont&#8230; o\u00f9 ils vont&#8230; d&rsquo;o\u00f9 ils viennent&#8230; ce qu&rsquo;ils font&#8230; de nous&#8230; je veux dire de vous ou moi, de vous et moi, bien s\u00fbr, \u00e9moi, \u00e9moi, et moi, et quoi ? Ce que j&rsquo;entends ? Ce que je vois ? Je ne sais pas. Et vous le savez-vous ? Je crois, oui, que vous le savez lorsque les mots sont enfin l\u00e0&#8230; parfois&#8230; par froid aussi parfois&#8230; Par temps de grand froid&#8230; Partant lorsqu&rsquo;ils sont l\u00e0&#8230; lorsqu&rsquo;ils sont enfin l\u00e0. Les mots&#8230; Ceux de Sylvie sont enfin l\u00e0&#8230; Ce sont ses mots \u00e0 elle&#8230; Ses mots d&rsquo;elle&#8230; Sylvie Godefroid. Voil\u00e0.<\/em><\/p>\n<p style=\"text-align: right;\">Francis Lalanne<\/p>\n<p><a href=\"http:\/\/www.meletout.net\/corrigeur\/wp-content\/uploads\/2018\/04\/Elle_et_Elle_Sylvie_Godefroid_HD.jpg\"><img loading=\"lazy\" class=\"alignleft wp-image-2242 \" src=\"http:\/\/www.meletout.net\/corrigeur\/wp-content\/uploads\/2018\/04\/Elle_et_Elle_Sylvie_Godefroid_HD-180x300.jpg\" alt=\"\" width=\"268\" height=\"447\" srcset=\"http:\/\/www.meletout.net\/corrigeur\/wp-content\/uploads\/2018\/04\/Elle_et_Elle_Sylvie_Godefroid_HD-180x300.jpg 180w, http:\/\/www.meletout.net\/corrigeur\/wp-content\/uploads\/2018\/04\/Elle_et_Elle_Sylvie_Godefroid_HD-614x1024.jpg 614w, http:\/\/www.meletout.net\/corrigeur\/wp-content\/uploads\/2018\/04\/Elle_et_Elle_Sylvie_Godefroid_HD.jpg 1578w\" sizes=\"(max-width: 268px) 100vw, 268px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Auteure :\u00a0<strong>Sylvie Godefroid<\/strong><br \/>\nPr\u00e9lude : <strong>Francis Lalanne<\/strong><br \/>\nTitre :\u00a0<strong>Elle et Elle<\/strong><br \/>\nIllustration :\u00a0<strong>Francis Lalanne<\/strong><br \/>\nEditeur :\u00a0<a href=\"http:\/\/www.lamiroy.be\/\"><strong>Lamiroy<\/strong><\/a><br \/>\nGenre :\u00a0<span style=\"color: #000000;\"><b>Recueil de po\u00e9sies<\/b><\/span><br \/>\nNombre de pages :\u00a0<strong>\u00a0127 pages<\/strong><br \/>\nNombre de mots\u00a0:\u00a0<strong>5.800<\/strong><span style=\"color: #333333;\"><strong>\u00a0mots<\/strong><\/span><\/p>\n<p><span style=\"color: #333333;\">Faire corriger un travail \u00e9quivalent\u00a0vous reviendrait \u00e0\u00a0<strong>50<\/strong><\/span><strong style=\"color: #333333;\">\u00a0\u20ac<\/strong><span style=\"color: #333333;\">, n\u2019h\u00e9sitez pas \u00e0 nous\u00a0<\/span><a title=\"Contact\" href=\"http:\/\/www.meletout.net\/corrigeur\/contact\/\">contacter<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Une femme qui souffre, une femme qui s&rsquo;ouvre&#8230; Le silence aussi parfois : celui de dire encore un peu ce qu&rsquo;elle peut ou veut&#8230; je crois&#8230; je ne sais pas&#8230; je lis&#8230; j&rsquo;\u00e9coute&#8230; Il ferait froid si les mots n&rsquo;\u00e9taient &hellip; <a href=\"http:\/\/www.meletout.net\/corrigeur\/sylvie-godefroid-elle-et-elle-2\/\">Continuer la lecture <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[2,4],"tags":[],"_links":{"self":[{"href":"http:\/\/www.meletout.net\/corrigeur\/wp-json\/wp\/v2\/posts\/2248"}],"collection":[{"href":"http:\/\/www.meletout.net\/corrigeur\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.meletout.net\/corrigeur\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.meletout.net\/corrigeur\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.meletout.net\/corrigeur\/wp-json\/wp\/v2\/comments?post=2248"}],"version-history":[{"count":4,"href":"http:\/\/www.meletout.net\/corrigeur\/wp-json\/wp\/v2\/posts\/2248\/revisions"}],"predecessor-version":[{"id":2262,"href":"http:\/\/www.meletout.net\/corrigeur\/wp-json\/wp\/v2\/posts\/2248\/revisions\/2262"}],"wp:attachment":[{"href":"http:\/\/www.meletout.net\/corrigeur\/wp-json\/wp\/v2\/media?parent=2248"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.meletout.net\/corrigeur\/wp-json\/wp\/v2\/categories?post=2248"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.meletout.net\/corrigeur\/wp-json\/wp\/v2\/tags?post=2248"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}